{"id":14078,"date":"2023-11-30T02:50:37","date_gmt":"2023-11-30T07:50:37","guid":{"rendered":"\/wp-content\/uploads\/2023\/11\/Cover.png"},"modified":"2023-11-30T02:50:37","modified_gmt":"2023-11-30T07:50:37","slug":"cover-5","status":"inherit","type":"attachment","link":"\/es\/cover-5\/","title":{"rendered":"Cover"},"author":191432658,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"class_list":["post-14078","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https://d1jeyrxw15fk4e.cloudfront.net/es/https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover.png'><img loading=\"lazy\" decoding=\"async\" width=\"232\" height=\"300\" src=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-232x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-232x300.png 232w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-791x1024.png 791w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-768x994.png 768w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-1187x1536.png 1187w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-1080x1398.png 1080w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-400x516.png 400w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-1280x1657.png 1280w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-980x1269.png 980w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-480x621.png 480w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover.png 1545w\" sizes=\"(max-width: 232px) 100vw, 232px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1545,"height":2000,"file":"2023\/11\/Cover.png","filesize":486000,"sizes":{"medium":{"file":"Cover-232x300.png","width":232,"height":300,"filesize":47437,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-232x300.png"},"large":{"file":"Cover-791x1024.png","width":791,"height":1024,"filesize":411837,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-791x1024.png"},"thumbnail":{"file":"Cover-150x150.png","width":150,"height":150,"filesize":23462,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-150x150.png"},"medium_large":{"file":"Cover-768x994.png","width":768,"height":994,"filesize":390522,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-768x994.png"},"1536x1536":{"file":"Cover-1187x1536.png","width":1187,"height":1536,"filesize":902429,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-1187x1536.png"},"et-pb-post-main-image":{"file":"Cover-400x250.png","width":400,"height":250,"filesize":103817,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-400x250.png"},"et-pb-post-main-image-fullwidth":{"file":"Cover-1080x675.png","width":1080,"height":675,"filesize":651934,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-1080x675.png"},"et-pb-portfolio-image":{"file":"Cover-400x284.png","width":400,"height":284,"filesize":115045,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-400x284.png"},"et-pb-portfolio-module-image":{"file":"Cover-510x382.png","width":510,"height":382,"filesize":180368,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-510x382.png"},"et-pb-portfolio-image-single":{"file":"Cover-1080x1398.png","width":1080,"height":1398,"filesize":749858,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-1080x1398.png"},"et-pb-gallery-module-image-portrait":{"file":"Cover-400x516.png","width":400,"height":516,"filesize":119389,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-400x516.png"},"et-pb-post-main-image-fullwidth-large":{"file":"Cover-1545x1800.png","width":1545,"height":1800,"filesize":1719185,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-1545x1800.png"},"et-pb-image--responsive--desktop":{"file":"Cover-1280x1657.png","width":1280,"height":1657,"filesize":1043583,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-1280x1657.png"},"et-pb-image--responsive--tablet":{"file":"Cover-980x1269.png","width":980,"height":1269,"filesize":619726,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-980x1269.png"},"et-pb-image--responsive--phone":{"file":"Cover-480x621.png","width":480,"height":621,"filesize":164874,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover-480x621.png"},"full":{"file":"Cover.png","width":1545,"height":2000,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/11\/Cover.png","filename":"Cover.png","filesize":486000,"_links":{"self":[{"href":"https:\/\/countrygal.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media\/14078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/countrygal.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/countrygal.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/countrygal.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/users\/191432658"}],"replies":[{"embeddable":true,"href":"https:\/\/countrygal.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/comments?post=14078"}]}}